{"id":15305,"date":"2020-11-14T22:44:33","date_gmt":"2020-11-14T21:44:33","guid":{"rendered":"http:\/\/www.alleyways.de\/abgeschminkt\/?p=15305"},"modified":"2020-11-14T22:45:28","modified_gmt":"2020-11-14T21:45:28","slug":"du-haettest-gehen-sollen-you-should-have-left","status":"publish","type":"post","link":"https:\/\/www.alleyways.de\/abgeschminkt\/2020\/du-haettest-gehen-sollen-you-should-have-left\/","title":{"rendered":"DVD\/Blu-ray: YOU SHOULD HAVE LEFT"},"content":{"rendered":"<p><a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/2020\/dvd-blu-ray-you-should-have-left\/you-should-have-left-1-copyright-universal-pictures\/\" rel=\"attachment wp-att-15311\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-15311 size-full\" title=\"You Should Have Left 1 - Copyright UNIVERSAL PICTURES\" src=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-1-Copyright-UNIVERSAL-PICTURES.jpg\" alt=\"You Should Have Left 1 - Copyright UNIVERSAL PICTURES\" width=\"231\" height=\"365\" srcset=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-1-Copyright-UNIVERSAL-PICTURES.jpg 231w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-1-Copyright-UNIVERSAL-PICTURES-190x300.jpg 190w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-1-Copyright-UNIVERSAL-PICTURES-127x200.jpg 127w\" sizes=\"auto, (max-width: 231px) 100vw, 231px\" \/><\/a><em>YOU SHOULD HAVE LEFT<\/em><br \/>\n<em>&#8211; auf DVD \/ Blu-ray<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Vor einigen Jahren etablierte sich der Begriff der Apatow-Schmiede. Es sind Kom\u00f6dien, die stark \u00fcber die Str\u00e4nge schlagen, immer perfekt mit den passenden Darstellern besetzt sind, ein Publikum haupts\u00e4chlich \u00fcber dem Teenager-Alter ansprechen, und sich trotz aller Geschmacklosigkeiten tats\u00e4chlich durch Tiefgang und Gehalt auszeichnen. Haben sich Erwachsene oder junge Erwachsene in den letzten Jahren mit z\u00fcgellosem Humor unterhalten, dann war es meist aus der Schmiede von Judd Apatow. Geschrieben, inszeniert, oder produziert, oder gleich alles zusammen. Diese Begrifflichkeit findet nun auch im Horrorgenre mit der Blumhouse-Schmiede eine angemessene Verwendung. Produzent Jason Blums Qualit\u00e4tsmerkmale: Experimentierfreude, Budgets \u00fcber dem Sparten-Standard, \u00fcberzeugende Variationen mit Versatzst\u00fccken des Genres, und Besetzungen mit namhaften Pers\u00f6nlichkeiten von au\u00dferhalb der Horrorschiene.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><!--more--><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Einst war der mittlerweile in die Jahre gekommene Theo ein angesehener Banker. Ein Ungl\u00fcck f\u00fcr das er f\u00e4lschlicherweise angeklagt war, hat seinen Ruf ruiniert und ihn aus der Bahn geworfen. Die Ehe mit der um einige Jahre j\u00fcngeren Susanna, und selbst die gemeinsame sechsj\u00e4hrige Tochter, scheinen seinem Gem\u00fctszustand wenig zutr\u00e4glich. Zudem leidet Theo unter gerechtfertigter Eifersucht. Kurz entschlossen mietet die dreik\u00f6pfige Familie ein Haus in der walisischen Provinz, um ihre Ehe auf Vordermann zu bringen und Abstand von ihrer Umwelt zu gewinnen. Doch das Haus, oder irgendetwas darin, hat etwas anderes f\u00fcr die Drei vorgesehen.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Es sollte nicht verwundern, wenn sich der Plot nach einem altbekannten Muster anh\u00f6rt. Weil es genau das ist, aber ganz offensichtlich auch sein will, und muss. YOU SHOULD HAVE LEFT macht im Grunde alles richtig. Und YOU SHOULD HAVE LEFT macht aber auch einiges falsch. Es ist die erste Verfilmung eines Romans von Daniel Kehlmann au\u00dferhalb Deutschlands. Und man m\u00f6chte glauben, dass dieser Roman bei diesem Produzenten, dem Drehbuchautoren und Regisseur, und dieser Besetzung, in den richtigen H\u00e4nden sein m\u00fcsste. Nach der Liste von Drehb\u00fcchern welche Regisseur David Koepp bisher verfasste, konnte YOU SHOULD HAVE LEFT nur eine sichere Sache sein.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Wie jeder gute Horrorfilm, nimmt sich auch dieser Zeit. Man m\u00f6chte schon behaupten, dass dies ein Blumhouse-Pr\u00e4dikat ist. Denn die Zeit ist gut genutzt. Die Charakterexposition f\u00fchrt sehr eindringlich vor Augen, wo und wie es innerhalb der Familie stockt. Die Figuren werden nicht einfach in die Terrorfalle geworfen, es ergibt sich alles sehr schl\u00fcssig. Theos ausgepr\u00e4gte Depression, der Verdacht auf Susannas Untreue. Die Drei nehmen viel mit in das anfangs unscheinbare Haus. Und dem Zuschauer bleibt einiges, worauf er seine eigenen Theorien bauen kann.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Schon die emotionalen Stimmungen zu Beginn sind sehr spannend, eben auf eine andere Weise. Doch dann kommen die bewegten Schatten wo keine sein d\u00fcrften, Konturen im Dunklen, die sich pl\u00f6tzlich bewegen, oder Spiegelbilder mit Eigenleben. David Koepp wei\u00df wie man Atmosph\u00e4re schafft und G\u00e4nsehaut erzeugt. Das tut er hervorragend. Obligatorische Jump-Scares sind selbstverst\u00e4ndlich, allerdings sehr mager eingesetzt, und entgegen dem \u00fcblichen Horror-Einerlei, ausnahmsweise verh\u00e4ltnism\u00e4\u00dfig und fundiert.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.alleyways.de\/abgeschminkt\/2020\/dvd-blu-ray-you-should-have-left\/you-should-have-left-3-copyright-universal-pictures\/\" rel=\"attachment wp-att-15313\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-15313 size-full\" title=\"You Should Have Left 3 - Copyright UNIVERSAL PICTURES\" src=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-3-Copyright-UNIVERSAL-PICTURES.jpg\" alt=\"You Should Have Left 3 - Copyright UNIVERSAL PICTURES\" width=\"640\" height=\"321\" srcset=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-3-Copyright-UNIVERSAL-PICTURES.jpg 640w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-3-Copyright-UNIVERSAL-PICTURES-300x150.jpg 300w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-3-Copyright-UNIVERSAL-PICTURES-200x100.jpg 200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Anderorts m\u00f6chte man YOU SHOULD HAVE LEFT immer mit der ersten Koepp und Bacon Zusammenarbeit ECHOES vergleichen. Das gelingt aber wirklich nur geringf\u00fcgig, und tut keinem der beiden Filme wirklich einen Gefallen. Beide haben jedoch eines gemein, und das ist Kevin Bacons inhaltlich perfektes Spiel. Sein Theo schwankt stets zwischen Verzweiflung und angehendem Wahnsinn, ohne das dies mit \u00fcberzogenen Reaktionen ausgespielt wird. Im Gegenteil, an einer die Handlung bestimmenden Sequenz ist er derart gegenl\u00e4ufig pragmatisch, dass es den Gruselfaktor sogar noch erh\u00f6ht.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Die Atmosph\u00e4re wird schlie\u00dflich so dicht, dass selbst in der Aufl\u00f6sung des l\u00e4ngst bekannten R\u00e4tsels \u00fcber die eigentliche Gr\u00f6\u00dfe des Hauses noch Schauer \u00fcber den R\u00fccken jagen. Aber warum will der eigentlich sorgsam und effektiv, wie effizient umgesetzte Film nicht richtig z\u00fcnden? Er funktioniert, sogar au\u00dferordentlich stimmungsvoll. Doch auf dieser Strecke hat der Beobachter noch einiges an Last zu tragen, das er nicht los zu werden scheint. Warum w\u00fcrde Susanna fremd gehen? Wieso wird der Altersunterschied stets so vehement hervorgehoben? Was macht Theo so passiv?<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Die Offenbarung um das Geheimnis des Hauses bietet eine fadenscheinige Erkl\u00e4rung, welche aber zu diesem Zeitpunkt kaum noch Wirkung zeigt, oder Relevanz besitzt. Die Substanz hat sich verfl\u00fcchtigt, in dem sich die Gewichtung bereits in der ersten H\u00e4lfte einseitig verschoben hat. Was dem Zuschauer bleibt ist immer noch ein sehr spannender, wirklich gruseliger Thriller. Aber es bleibt auch das stete Gef\u00fchl entlang des Weges, dass an entscheidenden Stellen viel mehr an inhaltlicher Stringenz und essenzieller Bedeutung m\u00f6glich gewesen w\u00e4re.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Das ist die hundertvierzigste Produktion f\u00fcr Jason Blum, der das Horrorgenre zweifellos f\u00fcr sich vereinnahmt hat. Weitere 31 Filme und TV-Serien sind bereits in Produktion, oder bereits gelaufen. Das ist erstaunlich, ist bewundernswert, und weckt Vorfreude. Es versteht sich von selbst, dass darunter einige filmische Missgeschicke fallen. Aber eben auch nicht wenige Instant-Klassiker. Und mittendrin Filme wie YOU SHOULD HAVE LEFT. Nicht bahnbrechend, aber ohne weiteres einen Besuch wert.<\/span><\/p>\n<p><a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/2020\/dvd-blu-ray-you-should-have-left\/you-should-have-left-2-copyright-universal-pictures\/\" rel=\"attachment wp-att-15312\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-15312 size-full\" title=\"You Should Have Left 2 - Copyright UNIVERSAL PICTURES\" src=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-2-Copyright-UNIVERSAL-PICTURES.jpg\" alt=\"You Should Have Left 2 - Copyright UNIVERSAL PICTURES\" width=\"640\" height=\"338\" srcset=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-2-Copyright-UNIVERSAL-PICTURES.jpg 640w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-2-Copyright-UNIVERSAL-PICTURES-300x158.jpg 300w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/You-Should-Have-Left-2-Copyright-UNIVERSAL-PICTURES-200x106.jpg 200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px;\"><em>Darsteller: <strong>Kevin Bacon, Amanda Seyfried, Avery Tiiu Essex, Colin Blumenau, Lowri Ann Richards, Joshua C. Jackson, Eli Powers<\/strong><\/em><br \/>\n<em>Regie &amp; Drehbuch:<strong> David Koepp<\/strong><\/em><br \/>\n<em>nach dem Roman von<strong> Daniel Kehlmann<\/strong><\/em><br \/>\n<em>Kamera:<strong> Angus Hudson<\/strong><\/em><br \/>\n<em>Bildschnitt: <strong>Derek Ambrosi<\/strong><\/em><br \/>\n<em>Musik: <strong>Geoff Zanelli<\/strong><\/em><br \/>\n<em>Produktionsdesign: <strong>Sophie Becher, Megan Elizabeth Bell<\/strong><\/em><br \/>\n<strong><em>Gro\u00dfbritannien &#8211; USA \/ 2020<\/em><\/strong><br \/>\n<em><strong>93<\/strong> Minuten<\/em><\/p>\n<h6>Bildrechte: <strong>UNIVERSAL PICTURES<\/strong><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>YOU SHOULD HAVE LEFT &#8211; auf DVD \/ Blu-ray Vor einigen Jahren etablierte sich der Begriff der Apatow-Schmiede. Es sind Kom\u00f6dien, die stark \u00fcber die Str\u00e4nge schlagen, immer perfekt mit den passenden Darstellern besetzt sind, ein Publikum haupts\u00e4chlich \u00fcber dem &hellip; <a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/2020\/du-haettest-gehen-sollen-you-should-have-left\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,6],"tags":[3369,3370,3368,536,148,1841,3367],"class_list":["post-15305","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-im-fernsehen-gesehen","tag-amamda-seyfrfied","tag-blumhouse","tag-du-haettest-gehen-sollen","tag-geisterhaus","tag-horror","tag-kevin-bacon","tag-you-should-have-left"],"_links":{"self":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/15305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/comments?post=15305"}],"version-history":[{"count":7,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/15305\/revisions"}],"predecessor-version":[{"id":15320,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/15305\/revisions\/15320"}],"wp:attachment":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/media?parent=15305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/categories?post=15305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/tags?post=15305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}