{"id":19884,"date":"2022-11-12T07:07:11","date_gmt":"2022-11-12T06:07:11","guid":{"rendered":"https:\/\/www.alleyways.de\/abgeschminkt\/?p=19884"},"modified":"2022-11-08T23:41:11","modified_gmt":"2022-11-08T22:41:11","slug":"mrs-harris-und-ein-kleid-von-dior-mrs-harris-goes-to-paris","status":"publish","type":"post","link":"https:\/\/www.alleyways.de\/abgeschminkt\/2022\/mrs-harris-und-ein-kleid-von-dior-mrs-harris-goes-to-paris\/","title":{"rendered":"Mrs HARRIS UND EIN KLEID VON DIOR"},"content":{"rendered":"<h3 style=\"text-align: right;\"><a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/mrs-harris-copyright-ada-films-ltd-harris-squared-kft\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-19881 size-full\" title=\"Mrs Harris - Copyright Ada Films Ltd - Harris Squared Kft\" src=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-Copyright-Ada-Films-Ltd-Harris-Squared-Kft.jpg\" alt=\"Mrs Harris - Copyright Ada Films Ltd - Harris Squared Kft\" width=\"258\" height=\"365\" srcset=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-Copyright-Ada-Films-Ltd-Harris-Squared-Kft.jpg 258w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-Copyright-Ada-Films-Ltd-Harris-Squared-Kft-212x300.jpg 212w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-Copyright-Ada-Films-Ltd-Harris-Squared-Kft-141x200.jpg 141w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" \/><\/a><strong>Mrs HARRIS GOES TO PARIS<\/strong><br \/>\n<strong>&#8211; Bundesstart 10.11.2022<\/strong><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Dies ist ein Film der direkt aus der Zeit zu kommen scheint, in der er spielt. 1958 erschien das Buch des amerikanischen Schriftstellers Paul Gallico, dem drei weitere Romane mit der selben Hauptfigur folgten. Es gab Fernsehfilme, auch B\u00fchnenfassungen, aber in all den Jahrzehnten blieb eine gr\u00f6\u00dfere Kinoproduktion aus. Regisseur Anthony Fabians Adaption verdeutlicht auch warum. Filme die auf humoristische Weise und im erz\u00e4hlerischen Stil den Geschichten von Mrs. Harris \u00e4hnlich sind, wurden seinerzeit am Flie\u00dfband produziert. Debbie Reynolds und Doris Day lassen mit Cary Grant und Jack Lemmon herzlich gr\u00fc\u00dfen, und dabei hat man sich dem deutschen Kom\u00f6dienalltag mit Heinz Erhardt noch nicht einmal angen\u00e4hert. Auf das despektierliche &#8218;Mrs. &#8218;Arris&#8216; im Titel hat man verzichtet, das wahrscheinlich den durchschnittlichen Franzosen weniger gest\u00f6rt h\u00e4tte, als den unbefriedigenden Moralapostel aus anderen Landen. Aber es geht auch nicht um Befindlichkeiten, sondern um den Geist einer anderen Zeit, den Anthony Fabian so wunderbar eingefangen hat.<\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Die Versuchung ist gro\u00df, Lesley Manville die beste Rolle ihrer bisherigen Laufbahn zu attestieren. Das ist die Figur der Ada Harris eigentlich nicht, aber eine gewisse \u00fcberschw\u00e4ngliche Begeisterung ergibt sich einfach aus dem Gesamtwerk. Dies ist dann wieder mit Manvilles unfassbarer Leichtigkeit zu spielen, unumst\u00f6\u00dflich verbunden. Die aufopferungsvolle Kriegswitwe Ada, die f\u00fcr wenig Lohn und noch weniger Anerkennung bei anderen Haushalten putzt.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ihre nicht zu unterdr\u00fcckende Neigung ist es, sich um andere zu k\u00fcmmern. Und selbst als sie fest entschlossen ist, endlich einmal etwas nur f\u00fcr sich zu tun, werden im Windschatten dieses Vorhabens Probleme anderer gel\u00f6st, oder deren Leben positiv ver\u00e4ndert. Fabian setzt das mit so entwaffnenden Charme in Szene, dass jeder auch die vorhersehbarsten Situationen mit verst\u00e4ndnisvollem L\u00e4cheln akzeptiert. Nicht &#8218;was&#8216; passiert ist handlungstechnisch vorgeschoben, sondern &#8218;wie&#8216; es passiert.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ada Harris m\u00f6chte als einfache, englische Putzfrau ein Kleid von Christian Dior. Zuerst ist es eine merkw\u00fcrdige Idee, woraus sich allerdings ein Traum bildet. Nur um einmal aus dem Leben auszubrechen, einmal sich die eigenen Leidenschaften erlauben. Der Film wird dabei zu keinem Zeitpunkt melancholisch, und wenn wir einmal mit unserer entt\u00e4uschten Heldin traurig werden, ist es nur ein Sto\u00dfseufzer. Von Anfang an sp\u00fcrt der Zuschauer, dass dies nicht der Film ist, wo es Niederlagen gibt.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Mrs. Harris verliert beim Hunderennen, ihr wird die Pensionskasse des verblichenen Gatten gestrichen, und selbst als sie einen wertvollen Juwel auf der Stra\u00dfe findet, gibt sie ihn ohne nachzudenken bei der Polizei ab. Mit jedem Verlust, der sie mehr und mehr von Dior in Paris fernzuhalten scheint, d\u00fcrfen wir gewahr sein, dass sich das Schicksal genau aus diesen Gr\u00fcnden zu Gunsten von Ada Harris entscheidet. Es ist ein Wohlf\u00fchlfilm aller erster G\u00fcte, dem man sogar die augenscheinlichsten Klischees verzeiht. Weil sie dazu geh\u00f6ren, und wir gefallen daran finden.<\/span><\/p>\n<p style=\"text-align: justify; padding-left: 40px;\"><em><span style=\"color: #000000;\">&#8222;Das Leben ist nicht immer Mondschein und Filme, Mrs. Harris!&#8220;<\/span><\/em><br \/>\n<em><span style=\"color: #000000;\">&#8222;Warum nicht?&#8220;<\/span><\/em><\/p>\n<p><a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/mrs-harris-goes-to-paris\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-19882 size-full\" title=\"Mrs Harris 1 - Copyright Ada Films Ltd - Harris Squared Kft\" src=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-1-Copyright-Ada-Films-Ltd-Harris-Squared-Kft.jpg\" alt=\"Mrs Harris 1 - Copyright Ada Films Ltd - Harris Squared Kft\" width=\"640\" height=\"427\" srcset=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-1-Copyright-Ada-Films-Ltd-Harris-Squared-Kft.jpg 640w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-1-Copyright-Ada-Films-Ltd-Harris-Squared-Kft-300x200.jpg 300w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-1-Copyright-Ada-Films-Ltd-Harris-Squared-Kft-200x133.jpg 200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Anthony Fabian hat das Buch zusammen mit Carroll Cartwright, Keith Thompson und Olivia Hetreed verfasst. Und sie haben genau verstanden worauf es ankommt. Nicht die kritische Satire eines Frank Capra aus den 30ern, sondern das vertr\u00e4umte Ideal eines Stanley Donen Anfang der 50er. Da wird nichts durch technische Tricks k\u00fcnstlich aufgepeppt, es gibt keine altklugen Querverweise auf soziopolitische Aktualit\u00e4ten, und die notwendige Diversit\u00e4t ist elegant auf ein realistisches Ma\u00df eigewoben, so dass es nicht nach anerkennender Aufmerksamkeit schreit.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">MRS. HARRIS ist ein Film, wie er ziemlich genau in jener Zeit gedreht worden w\u00e4re, in der er spielt. Und das ist erfrischend. Es ist selten, aber auch notwendig. Die Kamera von Felix Wiedemann ist der beste Freund der Geschichte. Kr\u00e4ftige Farben, akzentuierte Lichtsetzung, und eine erz\u00e4hlende Kameraf\u00fchrung. Mit ausgekl\u00fcgelten Einstellungen hebt Wiedemann wichtige Momente so geschickt hervor, dass diese Bilder nicht nur Ada Harris&#8216; Gef\u00fchlswelt wiederspiegeln, sondern wir es ebenso herausragend empfinden.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Es ist ein Film den jeder genie\u00dfen kann, weil er ehrlich ist. Auch wenn es paradox klingt, MRS. HARRIS ist besonders, weil er gar nicht besonders sein will. Durchweg unterhaltsam, manchmal naiv, aber immer charmant. Eine Geschichte die gut tut, weil solche Geschichten so rar geworden sind. Einen hohen Anspruch erf\u00fcllt der Film dadurch, dass er nicht schlauer sein will als wir Zuschauenden, und wir uns einfach einmal gepflegt unterhalten lassen k\u00f6nnen. Was mit der umwerfenden Lesley Manville auch unheimlich leicht f\u00e4llt.<\/span><\/p>\n<p style=\"text-align: justify; padding-left: 40px;\"><em><span style=\"color: #000000;\">&#8222;Das ist es, was du bist. Du bist eine Tr\u00e4umerin.&#8220; &#8211; Archie (Jason Isaacs)<\/span><\/em><\/p>\n<h6><a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/mrs-harris-goes-to-paris-2\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-19883 size-full\" title=\"Mrs Harris 2 - Copyright Ada Films Ltd - Harris Squared Kft\" src=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-2-Copyright-Ada-Films-Ltd-Harris-Squared-Kft.jpg\" alt=\"Mrs Harris 2 - Copyright Ada Films Ltd - Harris Squared Kft\" width=\"640\" height=\"301\" srcset=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-2-Copyright-Ada-Films-Ltd-Harris-Squared-Kft.jpg 640w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-2-Copyright-Ada-Films-Ltd-Harris-Squared-Kft-300x141.jpg 300w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Mrs-Harris-2-Copyright-Ada-Films-Ltd-Harris-Squared-Kft-200x94.jpg 200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/h6>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px;\">Darsteller: <strong>Lesley Manville, Isabelle Huppert, Lambert Wilson, Alba Baptista, Lucas Bravo, Ellen Thomas, Jason Isaac<\/strong> u.a.<br \/>\nRegie: <strong>Anthony Fabian<\/strong><br \/>\nDrehbuch: <strong>Anthony Fabian, Carroll Cartwright, Keith Thompson, Olivia Hetreed<\/strong><br \/>\nKamera: <strong>Felix Wiedemann<\/strong><br \/>\nBildschnitt: <strong>Barney Pilling<\/strong><br \/>\nMusik: <strong>Rael Jones<\/strong><br \/>\nProduktionsdesign: <strong>Luciana Arrighi<\/strong><br \/>\nGro\u00dfbritannien, Ungarn, USA, Frankreich, Kanada, Belgien<strong> \/ 2022<\/strong><br \/>\n<strong>115<\/strong> Minuten<\/p>\n<h6>Bildrechte:<strong> Ada Films Ltd &#8211; Harris Squared Kft<\/strong><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Mrs HARRIS GOES TO PARIS &#8211; Bundesstart 10.11.2022 Dies ist ein Film der direkt aus der Zeit zu kommen scheint, in der er spielt. 1958 erschien das Buch des amerikanischen Schriftstellers Paul Gallico, dem drei weitere Romane mit der selben &hellip; <a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/2022\/mrs-harris-und-ein-kleid-von-dior-mrs-harris-goes-to-paris\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,4],"tags":[261,4113,4111,4112,814],"class_list":["post-19884","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-im-kino-gesehen","tag-komodie","tag-lesley-manville-anthony-fabien","tag-mrs-harris-goes-to-paris","tag-mrs-harris-und-ein-kleid-von-dior","tag-romanze"],"_links":{"self":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/19884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/comments?post=19884"}],"version-history":[{"count":5,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/19884\/revisions"}],"predecessor-version":[{"id":19899,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/19884\/revisions\/19899"}],"wp:attachment":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/media?parent=19884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/categories?post=19884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/tags?post=19884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}