{"id":20748,"date":"2023-03-27T06:06:06","date_gmt":"2023-03-27T04:06:06","guid":{"rendered":"https:\/\/www.alleyways.de\/abgeschminkt\/?p=20748"},"modified":"2023-03-26T18:37:41","modified_gmt":"2023-03-26T16:37:41","slug":"shazam-fury-of-the-gods","status":"publish","type":"post","link":"https:\/\/www.alleyways.de\/abgeschminkt\/2023\/shazam-fury-of-the-gods\/","title":{"rendered":"SHAZAM! FURY OF THE GODS"},"content":{"rendered":"<h3 style=\"text-align: right;\"><a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/shazam-2-copyright-warner-bros\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-20742 \" title=\"Shazam 2 - Copyright WARNER BROS\" src=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-Copyright-WARNER-BROS.jpg\" alt=\"Shazam 2 - Copyright WARNER BROS\" width=\"310\" height=\"456\" srcset=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-Copyright-WARNER-BROS.jpg 405w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-Copyright-WARNER-BROS-204x300.jpg 204w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-Copyright-WARNER-BROS-136x200.jpg 136w\" sizes=\"auto, (max-width: 310px) 100vw, 310px\" \/><\/a><strong>&#8211; Bundesstart 16.03.2023<\/strong><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">SHAZAM! FURY OF THE GODS ist kein guter Film. Er ist sehr witzig, turbulent und opulent in seinen effektreichen und effektvollen Action-Sequenzen. Aber er ist weit von dem entfernt, was den ersten Teil so frisch, originell, rundherum einfach anders macht. Da hat Henry Gayden noch alleine das Drehbuch verfasst, nach Darren Lemkes Idee. Dieses mal muss sich Gayden den Titel mit Chris Morgan teilen, der sich haupts\u00e4chlich beim FAST &amp; FURIOUS Franchise exzessiv verausgabt hat. Und so einen Eindruck macht dann SHAZAM 2 auch, der eine ist den Part des Erwachsenwerdens zust\u00e4ndig, der andere f\u00fcr die \u00fcberfrachtete Action. \u00dcberfrachtet deswegen, weil die meisten Set-Pieces Schauwerte auffahren, die unmissverst\u00e4ndlich nur Gr\u00f6\u00dfe und Spektakel im Fokus haben. Ihre Opulenz wirkt aber immer wieder zu weit hergeholt, und um der Effekte willen dem Anspruch unangemessen aufgeblasen.<\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Billy Batson plagt die Sorgen, nach seinem nahenden achtzehnten Geburtstag das Haus der geliebten Pflegeeltern verlassen zu m\u00fcssen. Sein Alter Ego Shazam plagt die Sorge, dass seine Superhelden-Gruppe \u2013 die Shazamily &#8211; einfach nicht funktioniert, weil jeder mit dem Erwachsenwerden zu k\u00e4mpfen hat. Und das Publikum plagt die Sorge, warum der stattliche Superheld den ganzen zweiten Teil \u00fcber nach einem geeigneten Namen sucht, obwohl der eigentlich seit dem ersten Teil au\u00dfer Frage steht. Ein wunderbarer, augenzwinkernder Seitenhieb ist die Erw\u00e4gung f\u00fcr den Namen Captain Marvel. Leider ist nur Insider die Bedeutung dieses Namens in diesem Zusammenhang gel\u00e4ufig.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Die drei zornigen T\u00f6chter des Atlas holen sich den Zauberstab zur\u00fcck, den Shazam (noch ohne Namen) einen Ausgabe vorher zerbrochen hat. Mit ihm wollen sie einfach nur die Welt unterjochen und die Menschheit foltern und qu\u00e4len. Dazu brauchen sie die Energie eines Gottes oder Halbgottes, die ja der Superheld ohne Namen in sich tr\u00e4gt. Einhergeht damit ein weiterer Running-Gag der wirklich hervorragend umgesetzt ist. Denn eigentlich ist der von Djimon Hounsou gespielte Zauberer unwiederbringlich verstorben, aber f\u00fcr die Fortsetzung ohne jede Erkl\u00e4rung wieder am Leben. Das umgehen die Macher, indem die besten Freunde Billy und Freddy selbst Witze dar\u00fcber rei\u00dfen.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ja, der Witz in FURY OF THE GODS hat das Herz am rechten Fleck. Reihenweise Kalauer, unterschwellige Spitzen, deftiger Slapstick und selbstreferenzieller Humor. Das ist hervorragend, nur nicht auf das allumfassende, demografische Zielpublikum zugeschnitten, sondern bleibt leider unter der 20-Jahre-Grenze. So wie der gesamte Film, dramaturgisch und inhaltlich, f\u00fcr ein Publikum von Jugendlichen bis junge Erwachsene konzipiert ist. Was man dieser Altersgruppe aber auch zugestehen muss, es gibt schlie\u00dflich auch TOP GUN: MAVERICK f\u00fcr Leute wie den Schreiber dieser Zeilen. Nur das die Interessen des angesprochenen Publikums entweder halbherzig oder schlecht behandelt werden.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Viel zu nebens\u00e4chlich abgetan ist Superheldin Mary, die mit der ihr aufgeb\u00fcrdeten Verantwortung hadert, weil sie eigentlich ihren pers\u00f6nlichen Weg f\u00fcr die Zukunft finden m\u00f6chte. Noch letztes Jahr als die gro\u00dfe Hoffnung unter den Jungstars gefeiert, hinterl\u00e4sst Rachel Zegler einen merkw\u00fcrdig uninteressanten Eindruck, der Freddys haltlose Schw\u00e4rmerei nicht im Geringsten nachvollziehbar macht. Ist Jack Dylan Grazer als Freddy eigentlich die spannendste Figur in diesem Film, beschr\u00e4nkt ihn die Regie immer wieder auf den kauzigen Sidekick. Und mit einem unausgegoren eingesetzten Adam Brody als Super-Freddy, wird die gesamte Figur ihrer eigentlich tragischen M\u00f6glichkeiten nicht gerecht.<\/span><\/p>\n<p><a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/shazam-2-a-copyright-warner-bros\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-20743 size-full\" title=\"Shazam 2 a - Copyright WARNER BROS\" src=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-a-Copyright-WARNER-BROS.jpg\" alt=\"Shazam 2 a - Copyright WARNER BROS\" width=\"640\" height=\"369\" srcset=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-a-Copyright-WARNER-BROS.jpg 640w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-a-Copyright-WARNER-BROS-300x173.jpg 300w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-a-Copyright-WARNER-BROS-200x115.jpg 200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Man kann dank des gen\u00fcgsamen Unterhaltungswertes \u00fcber so einige Schwachstellen hinwegsehen. Au\u00dfer der Kompatibilit\u00e4t zwischen den Hauptdarstellern Asher Angel und Zachary Levi, die trotz des selben Charakters ganz andere Wesensz\u00fcge tragen. Jeder f\u00fcr sich ist wunderbar, aber als koh\u00e4sive Figur funktionieren sie seltsamerweise nicht mehr. Daf\u00fcr h\u00e4tte Drache Ladon eine signifikantere Rolle einnehmen k\u00f6nnen. W\u00e4hrend die anderen menschbedrohenden Kreaturen dem 08\/15-Design der Fantasy entsprechen, ist Ladon beeindruckend imposant. Als W\u00e4chter des Hesperidengartens h\u00e4tte er wesentlich mehr vertragen, als nur das stupid brachiale Unwesen.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Das die Macher (noch nicht ganz von James Gunns Visionen beeinflusst) den erwachsenen Anteil erh\u00f6ht haben, ist schade, weil das Herausstellungsmerkmal von SHAZAM eben die unbek\u00fcmmerte und nat\u00fcrlich naive Art des Superhelden war, wo das Hauptaugenmerk eben einmal nicht auf der Rettung des Universums lag. Aber schon jetzt ist das Schicksal dieses Heldens unwiederbringlich in DCs zusammenfassenden Universum festgelegt, obwohl Zachary Levi bis jetzt noch nicht im DCEU-Neustart THE FLASH aufzutreten scheint. Wobei die vielen dahingehenden Spitzen und Querverweise clever und ad\u00e4quat die ohnehin saloppe Stimmung aufwerten.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Das allerdings ein bis zum Ende f\u00fcr die eigentliche Handlung nicht relevanter Charakter entscheidend die letzten Minuten bestimmt, ist f\u00fcr die Handlungsdramaturgie eine sehr ungl\u00fcckliche Entscheidung. Noch fragw\u00fcrdiger ist allerdings das grunds\u00e4tzliche Narrativ, welches dem von Zack Snyders MAN OF STEEL gleichkommt. Die Superhelden sind als \u201aPhilly Fiascos\u2018 in der \u00d6ffentlichkeit verschrien, obwohl sie tats\u00e4chlich Leben retten. Sie erfahren paradoxerweise erst den Respekt und Jubel der Menschen, als diese von den t\u00f6dlichen Bedrohungen besch\u00fctzt werden, f\u00fcr die aber die Shazamily ganz klar verantwortlich ist.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">SHAZAM! FURY OF THE GODS ist kein guter Film. Er ist opulent, turbulent und sehr witzig ausgestattet (Die Horrorpuppe Annabelle sitzt bei einem Kinderarzt kurz im Hintergrund). So viel Gutes mit originellen Ideen steckt darin, allerdings ergibt es im Ablauf ein unbefriedigendes St\u00fcckwerk. Es w\u00e4re m\u00f6glich gewesen die Schw\u00e4chen und Logikl\u00f6cher auszugleichen, worauf aber auch in der Nachproduktion offensichtlich kein Wert gelegt wurde. Das macht aus einem guten Film eine vertane Chance. Vom Grauen der deutschen Synchronisation muss man da gar nicht erst anfangen. Sch\u00e4men sollten sie die deutschen Auftraggeber.<\/span><\/p>\n<p><a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/shazam-2-b-copyright-warner-bros\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-20744 size-full\" title=\"Shazam 2 b- Copyright WARNER BROS\" src=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-b-Copyright-WARNER-BROS.jpg\" alt=\"Shazam 2 b- Copyright WARNER BROS\" width=\"640\" height=\"362\" srcset=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-b-Copyright-WARNER-BROS.jpg 640w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-b-Copyright-WARNER-BROS-300x170.jpg 300w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Shazam-2-b-Copyright-WARNER-BROS-200x113.jpg 200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px;\">Darsteller:<strong> Zachary Levi, Asher Angel, Adam Brody, Jack Dylan Grazer, Ross Butler, Ian Chen, Rachel Zegler, Helen Mirren, Lucy Liu, Djimon Hounsou, Meagan Good, Grace Carolina Currey<\/strong> u.a.<br \/>\nRegie: <strong>David F. Sandberg<\/strong><br \/>\nDrehbuch: <strong>Henry Gayden, Chris Morgan<\/strong><br \/>\nnach<strong> Bill Parker <\/strong>und<strong> C.C. Beck<\/strong><br \/>\nKamera: <strong>Gyula Pados<\/strong><br \/>\nBildschnitt: <strong>Michel Aller<\/strong><br \/>\nMusik: <strong>Christophe Beck<\/strong><br \/>\n<strong>USA \/ 2023<\/strong><br \/>\n<strong>130<\/strong> Minuten<\/p>\n<h6>Bildrechte: <strong>WARNER BROS<\/strong><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Bundesstart 16.03.2023 SHAZAM! FURY OF THE GODS ist kein guter Film. Er ist sehr witzig, turbulent und opulent in seinen effektreichen und effektvollen Action-Sequenzen. Aber er ist weit von dem entfernt, was den ersten Teil so frisch, originell, rundherum &hellip; <a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/2023\/shazam-fury-of-the-gods\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,4],"tags":[430,282,601,825,2944,58,4283,589,4284],"class_list":["post-20748","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-im-kino-gesehen","tag-abenteuer","tag-action","tag-dc","tag-helen-mirren","tag-lucy-liu","tag-sequel","tag-shazam-fury-of-the-gods","tag-superheroes","tag-zachary-levi"],"_links":{"self":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/20748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/comments?post=20748"}],"version-history":[{"count":5,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/20748\/revisions"}],"predecessor-version":[{"id":20785,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/20748\/revisions\/20785"}],"wp:attachment":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/media?parent=20748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/categories?post=20748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/tags?post=20748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}