{"id":8625,"date":"2015-02-12T02:00:26","date_gmt":"2015-02-12T01:00:26","guid":{"rendered":"http:\/\/www.alleyways.de\/abgeschminkt\/?p=8625"},"modified":"2015-02-11T22:48:55","modified_gmt":"2015-02-11T21:48:55","slug":"inherent-vice-natuerliche-maengel","status":"publish","type":"post","link":"https:\/\/www.alleyways.de\/abgeschminkt\/2015\/inherent-vice-natuerliche-maengel\/","title":{"rendered":"INHERENT VICE &#8211; Nat\u00fcrliche M\u00e4ngel"},"content":{"rendered":"<p><em>INHERENT VICE &#8211; Bundesstart 12.02.2015<\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/?attachment_id=8617\" rel=\"attachment wp-att-8617\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8617\" title=\"Copyright Warner Bros.\" alt=\"Inherent-Vice-1, Copyright Warner Bros.\" src=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Inherent-Vice1.jpg\" width=\"300\" height=\"424\" srcset=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Inherent-Vice1.jpg 300w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Inherent-Vice1-141x200.jpg 141w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Inherent-Vice1-212x300.jpg 212w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><span style=\"color: #000000;\">Larry &#8218;Doc&#8216; Sportello ist Privatdetektiv im fiktiven Gordita Beach. Es ist 1970, eine Zeit wo es eigentlich immer M\u00f6glichkeit zur Bewusstseinserweiterung gab. Und Doc nutzt diese M\u00f6glichkeit auch unentwegt. Seinen Spitznamen hat Sportello dem Umstand zu verdanken, dass sein B\u00fcro im hintersten Winkel einer Privatklinik untergebracht ist. Warum Romanautor Thomas Pynchon ein St\u00e4dtchen erfinden musste, das mit jeder Pore Venice Beach atmet, inklusive aller seiner Sub-Kulturen, das bleibt nur vordergr\u00fcndig ein R\u00e4tsel. Wenngleich kein anderer Stadtteil im Gro\u00dfraum Los Angeles so widerspr\u00fcchlich, abwechslungsreich, und undurchsichtig bis zum heutigen Tag ist, wollte selbst Pynchon, und Regisseur Anderson noch weniger, einer ganzen Lebensgemeinschaft mit ihrer ganz eigenen Lebensauffassung auf den nicht getragenen Schlips treten wollten. Daf\u00fcr kann man davon ausgehen, dass auch Gordita Beach, wie sein nicht zu greifendes Vorbild, heute nichts von seinem verwirrenden Charme verloren h\u00e4tte. Mit Typen wie Larry &#8218;Doc&#8216; Sportello bestimmt nicht. Dieser wird von seiner Ex-Freundin Shasta aufgesucht, die ein Komplott gegen ihren Liebhaber, den Immobilienspekulanten Michael Wolfman vermutet. Angeblich planen Wolfmans Frau und deren Liebhaber, den Million\u00e4r in ein psychiatrisches Institut einweisen, und ihn damit entm\u00fcndigen zu k\u00f6nnen.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><!--more-->Ganz offensichtlich gefiel Thomas Pynchon die Idee, den Hardboiled-Krimi von Ross Macdonald oder Dashiell Hammett, von der Unterwelt in ein absurdes Panoptikum von Hippies, Gro\u00dfspekulanten, Nazi-Gruppen und Prostitution zu heben. Von zwielichtigen Bars und dunklen Seitenstra\u00dfen, hinaus in eine unkontrollierbare bunte Welt von freier Liebe und von Drogen zerfressene Egos. Und man sp\u00fcrt die Begeisterung, mit welcher sich Paul Thomas Anderson dieser Aufgabe hingegeben hat. Nymphomaninnen, oral fixierte Polizisten, von Drogen zerst\u00f6rte Drogenberater, Juden die sich mit Rechtsextremen umgeben, und Rechtsextreme, die Gesch\u00e4fte mit schwarzen B\u00fcrgerrechtlern machen. Oder ein Zahnarzt au\u00dfer Kontrolle, eine Staatsanw\u00e4ltin ohne Skrupel, und ein Saxophon-Spieler, den niemand erkennt, weil er sich als Bass-Spieler ausgibt. Das Docs Anwalt ein Anwalt f\u00fcr Seerecht ist, macht dann das eigenwillige Panoptikum noch perfekt.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Und in dieser Welt voller \u00fcberdrehter Charaktere, gibt es lediglich eine Konstante, und das ist Larry &#8218;Doc&#8216; Sportello, gerade weil man von ihm erwartet, die unzuverl\u00e4ssigste Person im Spiel zu sein. Das Problem ist Andersons Absicht, nicht nur zwei Genres zu mischen, sondern eines davon gleich komplett aufzubrechen. Das eine ist die Satire, die leidlich funktioniert. Das andere ist der Krimi, der hier keine verschlungenen Pfade geht, keine fintenreiche Wendungen bereit h\u00e4lt, und keine d\u00fcsteren Geheimnisse preis gibt. Anderson ist an den Figuren interessiert, und nicht an der sich an den Film-Noir orientierenden Handlungsaufbau. So wird aus dem vorgeblichen Krimi, ein Abfolge von sich erg\u00e4nzenden Episoden. &#8218;Doc&#8216; wird mal hier angeheuert, was zuf\u00e4llig wieder zu dem verschwundenen Wolfman f\u00fchrt, oder er wird von anderer Seite kontaktiert, was ihn erneut Wolfman n\u00e4her bringt. Die Struktur von INHERENT VICE kommt einem Flipper-Automaten gleich. Der Ball prallt an verschiedenen Hindernissen ab, wird hin und her geschossen, sammelt dabei Punkte, und geht dann mit High-Score irgendwann ins Aus. Zum spekulieren, oder mit r\u00e4tseln ist die Geschichte gewiss nicht. Selbst &#8218;Doc&#8216; wird immer wieder vor vollendete Tatsachen gestellt, anstatt man ihm sein Schn\u00fcffeln\u00e4schen einmal f\u00fcr etwas anderes zugesteht, als eine Line zu ziehen.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Paul Thomas Anderson ist eben an seinen Figuren interessiert. THERE WILL BE BLOOD oder THE MASTER sind daf\u00fcr seine eindringlichsten Beispiele. Seinen Humor bezieht der Film aus diesen Figuren, die allesamt eine ganze Spur zu \u00fcberspannt sind. Wo die Wirklichkeit Halt machen w\u00fcrde, setzen die Charaktere in INHERENT VICE immer noch eins drauf. So als wollte Anderson, wie vielleicht von Pynchon beabsichtigt, vornehmlich einer \u00c4ra Tribut zollen, in der Drogenkonsum relativ war. Das hat allerdings oft einmal einen unpassenden Slapstick-Charakter, wo der Regisseur scheinbar die Grenzen innerhalb seiner Inszenierung nicht mehr im Blick hatte. So wie die Sequenz, wo &#8218;Doc&#8216; von einem gro\u00dfen Polizeiaufgebot verfolgt wird, welches versucht unsichtbar zu bleiben. Und wenn Joaquin Phoenix einen in einer Einstellung gedrehten Dialog \u00fcber sechs Minuten f\u00fchrt, wo Katherine Waterston splitternackt neben ihm sitzt, dann hat das viel mehr verst\u00f6rendes als am\u00fcsantes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Gerade die Dialogsequenzen sind eine echte Herausforderung f\u00fcr den Zuschauer. Anderson l\u00e4sst seine Darsteller reden, sehr lange. Er l\u00e4sst sie ihre Szenen richtig ausspielen, und das zum gr\u00f6\u00dften Teil ohne einen einzigen Schnitt. Hier wird sich das Publikum spalten, welches auf der einen Seite INHERENT VICE als Meisterwerk preisen wird, und anderseits als z\u00e4hes, viel zu langatmiges Kunstobjekt geschm\u00e4ht werden wird. W\u00e4hrend man beide Kritikpunkte gelten lassen muss. INHERENT VICE ist ein viel zu langer Film, der die Geduld seines Publikums durchaus auf die Probe stellen kann. Daf\u00fcr ist er ein k\u00fcnstlerisches Gesamtkunstwerk, mit sehr hohem Unterhaltungswert. Wenn &#8218;Doc&#8216; mit einem neuen Hinweis auf den Nullpunkt zur\u00fcck geworfen wird, steht er unvermittelt im dichten Nebel, und findet seinen Weg nicht zur\u00fcck. Das sind f\u00fcr gew\u00f6hnlich unterst\u00fctzende Stilmittel ambitionierter Filmstudenten. Bei Anderson sind das l\u00e4stige Stolpersteine, die sich den Charaktere zus\u00e4tzlich in den Weg legen. Er unterst\u00fctzt nicht die Szene, sondern mokiert sich \u00fcber die Figur, als w\u00e4re es eine sichtbare Reaktion des Zuschauers.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">So langatmig und soviel k\u00fcrzer INHERENT VICE sein k\u00f6nnte, und auch seinen Krimi-Plot nur m\u00e4\u00dfig beherrscht, gibt es bei dem Film doch sehr viel zu entdecken. So bunt und zusammengew\u00fcrfelt die Figuren sind, genauso wie die verschiedenen Handlungspunkte ein Mix von vielen m\u00f6glichen Absurdit\u00e4ten darstellen, ist der Unterhaltungswert zweifellos sehr hoch. Und einmal ehrlich, allein dieser Backenbart, den wirklich kein anderer so glaubw\u00fcrdig tragen kann, wie Joaquin Phoenix.<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/?attachment_id=8618\" rel=\"attachment wp-att-8618\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8618\" title=\"Copyright Warner Bros.\" alt=\"INHERENT VICE - 2, Copyright Warner Bros.\" src=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Inherent-Vice-2.jpg\" width=\"620\" height=\"438\" srcset=\"https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Inherent-Vice-2.jpg 620w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Inherent-Vice-2-200x141.jpg 200w, https:\/\/www.alleyways.de\/abgeschminkt\/wp-content\/uploads\/Inherent-Vice-2-300x211.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p style=\"padding-left: 60px;\"><em>Darsteller: Joaquin Phoenix, Josh Brolin, Owen Wilson, Reese Witherspoon, Katherine Waterstone, Benicio del Toro, Jena Malone u.a.<\/em><br \/>\n<em> Regie &amp; Drehbuch: Paul Thomas Anderson, nach dem Buch von Thomas Pynchon<\/em><br \/>\n<em> Kamera: Robert Elswit<\/em><br \/>\n<em> Bildschnitt: Leslie Jones<\/em><br \/>\n<em> Musik: Johnny Greenwood<\/em><br \/>\n<em> Produktionsdesign: David Crank<\/em><br \/>\n<em> USA \/ 2014<\/em><br \/>\n<em> 148 Minuten<\/em><\/p>\n<h5>Bildrechte: <strong>Warner Bros.<\/strong><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>INHERENT VICE &#8211; Bundesstart 12.02.2015 Larry &#8218;Doc&#8216; Sportello ist Privatdetektiv im fiktiven Gordita Beach. Es ist 1970, eine Zeit wo es eigentlich immer M\u00f6glichkeit zur Bewusstseinserweiterung gab. Und Doc nutzt diese M\u00f6glichkeit auch unentwegt. Seinen Spitznamen hat Sportello dem Umstand &hellip; <a href=\"https:\/\/www.alleyways.de\/abgeschminkt\/2015\/inherent-vice-natuerliche-maengel\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,4],"tags":[171,1634,796,1635,132],"class_list":["post-8625","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-im-kino-gesehen","tag-drama","tag-inherent-vice","tag-joaquin-phoenix","tag-natuerliche-maengel","tag-reese-witherspoon"],"_links":{"self":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/8625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/comments?post=8625"}],"version-history":[{"count":7,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/8625\/revisions"}],"predecessor-version":[{"id":8686,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/posts\/8625\/revisions\/8686"}],"wp:attachment":[{"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/media?parent=8625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/categories?post=8625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alleyways.de\/abgeschminkt\/wp-json\/wp\/v2\/tags?post=8625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}